{"id":18233,"date":"2024-04-16T15:22:22","date_gmt":"2024-04-16T15:22:22","guid":{"rendered":"https:\/\/systematic-erp.com\/?p=18233"},"modified":"2024-05-27T13:29:26","modified_gmt":"2024-05-27T13:29:26","slug":"systematic-hebergement-le-digital-nouvelle-arme-des-foyers-universitaires","status":"publish","type":"post","link":"https:\/\/systematic-erp.com\/ar\/2024\/04\/16\/systematic-hebergement-le-digital-nouvelle-arme-des-foyers-universitaires\/","title":{"rendered":"Systematic | H\u00e9bergement : Le digital, nouvelle arme des foyers universitaires"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"18233\" class=\"elementor elementor-18233\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c1c34bd e-flex e-con-boxed e-con e-parent\" data-id=\"c1c34bd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8cfaa66 elementor-widget elementor-widget-image\" data-id=\"8cfaa66\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"774\" src=\"https:\/\/systematic-erp.com\/wp-content\/uploads\/2022\/04\/ARTICLE-la-presse-1024x774.jpeg\" class=\"attachment-large size-large wp-image-5702\" alt=\"\" srcset=\"https:\/\/systematic-erp.com\/wp-content\/uploads\/2022\/04\/ARTICLE-la-presse-1024x774.jpeg 1024w, https:\/\/systematic-erp.com\/wp-content\/uploads\/2022\/04\/ARTICLE-la-presse-300x227.jpeg 300w, https:\/\/systematic-erp.com\/wp-content\/uploads\/2022\/04\/ARTICLE-la-presse-768x581.jpeg 768w, https:\/\/systematic-erp.com\/wp-content\/uploads\/2022\/04\/ARTICLE-la-presse-1536x1161.jpeg 1536w, https:\/\/systematic-erp.com\/wp-content\/uploads\/2022\/04\/ARTICLE-la-presse-2048x1548.jpeg 2048w, https:\/\/systematic-erp.com\/wp-content\/uploads\/2022\/04\/ARTICLE-la-presse-330x250.jpeg 330w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b72a45f elementor-widget elementor-widget-text-editor\" data-id=\"b72a45f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tSystematech e r\u00e9ussi \u00e0 cr\u00e9er une plate-forme en ligne qui offre des solutions d\u2019h\u00e9bergement adapt\u00e9es aux besoins des \u00e9tudiants et surtout des foyers universitaires.\nLe coup d\u2019envoi de l\u2019ann\u00e9e universitaire a \u00e9t\u00e9 donn\u00e9 il y a quelques semaines, dans un contexte particulier li\u00e9 \u00e0 l\u2019\u00e9pi\u00acd\u00e9mie de Covid-19. Mais comme de coutume, le parcours s\u2019annonce assez p\u00e9nible pour les \u00e9tudiants, les \u00e9tablis\u00acsements et foyers universitaires qui doivent surmonter plusieurs obstacles d\u2019ordre organisationnel sans oublier les demandes d\u2019h\u00e9bergement dans les cit\u00e9s universitaires qui deviennent un probl\u00e8me r\u00e9curent et mondial avec notamment la propagation du coronavi\u00acrus dans le monde entier, cette crise qui peut changer de nombreuses choses du jour au lendemain.\n<h3 style=\"margin: 0cm 0cm 12.0pt 0cm;\"><strong><span style=\"font-family: 'Arial',sans-serif;\">Transformer la crise en opportunit\u00e9<\/span><\/strong><\/h3>\nMalgr\u00e9 cette situation particuli\u00e8re, nos jeunes comp\u00e9tences ont r\u00e9ussi encore une fois \u00e0 \u00e9tendre leur action en amont. Ces derni\u00e8res ne cessent de nous surprendre avec des id\u00e9es inno\u00advantes et surprenantes\u2026 Chaque jour, on d\u00e9couvre le potentiel cach\u00e9 de ces jeunes avec des solutions qui viennent de partout et souvent de l\u00e0 o\u00f9 on ne les attend pas. C\u2019est en fait le cas de Syste\u00admatech, une soci\u00e9t\u00e9 tuniso-am\u00e9ricaine cr\u00e9\u00e9e par le Tunisien Mohamed Lassa\u00e2d Na\u00e2s, ing\u00e9nieur informatique sp\u00e9cialiste de la syst\u00e9matique.\n\nCompos\u00e9e d\u2019une \u00e9quipe 100% tuni\u00adsienne, Systematech a r\u00e9ussi \u00e0 cr\u00e9er une plateforme en ligne qui offre des solutions d\u2019h\u00e9bergement adapt\u00e9es aux besoins des \u00e9tudiants et surtout des foyers universitaires. \u00abAu lieu de regret\u00adter un pass\u00e9 plus glorieux, on devrait se tourner vers l\u2019avenir\u2026 Cette crise sanitaire pourrait se transformer en opportunit\u00e9 pour tous les op\u00e9rateurs, tous les domaines et tous les secteurs d\u2019activit\u00e9\u2026 L\u2019id\u00e9e est de profiter de cette crise pour s\u2019engager dans des voies qui seront p\u00e9rennes et capables de renver\u00adser la situation dans un futur proche\u00bb, indique Mohamed Lassa\u00e2d Na\u00e2s, dans une d\u00e9claration accord\u00e9e \u00e0\u00a0<em>La Presse.<\/em>\n\n\u00abMyHouse\u00bb, permet de digitaliser les services des \u00e9tablissements d\u2019h\u00e9ber\u00adgement universitaires, ce qui va faciliter leur \u00e9change avec les \u00e9tudiants dans les quatre coins du monde, ces der\u00adniers peuvent soumettre une requ\u00eate d\u2019h\u00e9bergement, recevoir l\u2019accord d\u2019af\u00adfectation \u00e0 un foyer universitaire, payer l\u2019h\u00e9bergement\u2026ce qui ne n\u00e9cessite pas de d\u00e9placement sur place. C\u2019est r\u00e9ciproque pour les foyers universitaires, pour lesquels, cette solution assurera et facilitera aux \u00e9tudiants de bonnes conditions d\u2019h\u00e9bergement et d\u2019accueil gr\u00e2ce \u00e0 sa souplesse, sa facilit\u00e9 d\u2019utili\u00adsation, les nombreuses fonctionnalit\u00e9s qu\u2019elle permet et, surtout, \u00e0 la possibilit\u00e9 d\u2019\u00eatre int\u00e9gr\u00e9e \u00e0 distance. \u00abMyHouse est parmi les rares solutions innovantes au monde qui offrent un tel avantage. A peine quelques mois apr\u00e8s le lance\u00adment de ce produit, nous sommes fiers aujourd\u2019hui d\u2019une r\u00e9ussite qui d\u00e9passe les attentes et les fronti\u00e8res\u2026 Apr\u00e8s une d\u00e9monstration qui a \u00e9t\u00e9 faite \u00e0 la demande de la Maison de Tunisie en France, notre solution a r\u00e9ussi \u00e0 s\u00e9duire plusieurs \u00e9tablissements, membres de la Cit\u00e9 internationale universitaire de Paris (Ciup), outre des Fondations des Etats-Unis et d\u2019Allemagne qui viennent attester de l\u2019int\u00e9r\u00eat et du caract\u00e8re incontournable d\u2019avoir recours \u00e0 notre solution\u00bb, explique-t-il. Pour la Tunisie, Na\u00e2s indique que pour l\u2019instant, ce qui manque, c\u2019est la volont\u00e9 des autorit\u00e9s et du secteur priv\u00e9 pour d\u00e9velopper cette solution aupr\u00e8s des nos foyers universitaires qui trouvent des difficult\u00e9s \u00e0 r\u00e9pondre \u00e0 toutes les demandes des \u00e9tudiants en la mati\u00e8re. Mais Systema\u00adtech est et restera toujours ouverte et pr\u00eate \u00e0 toute collaboration avec les parties prenantes pour leur offrir une solution innovante de gestion des h\u00e9ber\u00adgements, capable de donner une bouf\u00adf\u00e9e d\u2019oxyg\u00e8ne aux foyers universitaires et aux \u00e9tudiants qui devraient effectuer un parcours de combattant pour avoir un foyer.\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n\nLa Presse de Tunisie \u2013 Lundi 26 octobre 2020\n\n<cite><strong>Meriem KHDIMALLAH<\/strong><\/cite><\/blockquote>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Systematech e r\u00e9ussi \u00e0 cr\u00e9er une plate-forme en ligne qui offre des solutions d\u2019h\u00e9bergement adapt\u00e9es aux besoins des \u00e9tudiants et surtout des foyers universitaires. Le coup d\u2019envoi de l\u2019ann\u00e9e universitaire a \u00e9t\u00e9 donn\u00e9 il y a quelques semaines, dans un contexte particulier li\u00e9 \u00e0 l\u2019\u00e9pi\u00acd\u00e9mie de Covid-19. Mais comme de coutume, le parcours s\u2019annonce assez [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":16694,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"footnotes":""},"categories":[77],"tags":[],"class_list":["post-18233","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-77"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Systematic | H\u00e9bergement : Le digital, nouvelle arme des foyers universitaires - Systematic ERP<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/systematic-erp.com\/ar\/2024\/04\/16\/systematic-hebergement-le-digital-nouvelle-arme-des-foyers-universitaires\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Systematic | H\u00e9bergement : Le digital, nouvelle arme des foyers universitaires - Systematic ERP\" \/>\n<meta property=\"og:description\" content=\"Systematech e r\u00e9ussi \u00e0 cr\u00e9er une plate-forme en ligne qui offre des solutions d\u2019h\u00e9bergement adapt\u00e9es aux besoins des \u00e9tudiants et surtout des foyers universitaires. Le coup d\u2019envoi de l\u2019ann\u00e9e universitaire a \u00e9t\u00e9 donn\u00e9 il y a quelques semaines, dans un contexte particulier li\u00e9 \u00e0 l\u2019\u00e9pi\u00acd\u00e9mie de Covid-19. Mais comme de coutume, le parcours s\u2019annonce assez [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/systematic-erp.com\/ar\/2024\/04\/16\/systematic-hebergement-le-digital-nouvelle-arme-des-foyers-universitaires\/\" \/>\n<meta property=\"og:site_name\" content=\"Systematic ERP\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SystematicSoftwareSolutions\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-16T15:22:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-27T13:29:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/systematic-erp.com\/wp-content\/uploads\/2022\/04\/La-presse-Le-digital-nouvelle-arme-des-foyers-universitaires-systematic.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"570\" \/>\n\t<meta property=\"og:image:height\" content=\"396\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u0643\u064f\u062a\u0628 \u0628\u0648\u0627\u0633\u0637\u0629\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u0648\u0642\u062a \u0627\u0644\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u064f\u0642\u062f\u0651\u0631\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 \u062f\u0642\u0627\u0626\u0642\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/systematic-erp.com\\\/ar\\\/2024\\\/04\\\/16\\\/systematic-hebergement-le-digital-nouvelle-arme-des-foyers-universitaires\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/systematic-erp.com\\\/ar\\\/2024\\\/04\\\/16\\\/systematic-hebergement-le-digital-nouvelle-arme-des-foyers-universitaires\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/systematic-erp.com\\\/#\\\/schema\\\/person\\\/010337d3b3ba99dbdb74deb2c65423db\"},\"headline\":\"Systematic | H\u00e9bergement : Le digital, nouvelle arme des foyers universitaires\",\"datePublished\":\"2024-04-16T15:22:22+00:00\",\"dateModified\":\"2024-05-27T13:29:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/systematic-erp.com\\\/ar\\\/2024\\\/04\\\/16\\\/systematic-hebergement-le-digital-nouvelle-arme-des-foyers-universitaires\\\/\"},\"wordCount\":694,\"image\":{\"@id\":\"https:\\\/\\\/systematic-erp.com\\\/ar\\\/2024\\\/04\\\/16\\\/systematic-hebergement-le-digital-nouvelle-arme-des-foyers-universitaires\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/systematic-erp.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/La-presse-Le-digital-nouvelle-arme-des-foyers-universitaires-systematic.jpg\",\"articleSection\":[\"\u0635\u062d\u0627\u0641\u0629\"],\"inLanguage\":\"ar\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/systematic-erp.com\\\/ar\\\/2024\\\/04\\\/16\\\/systematic-hebergement-le-digital-nouvelle-arme-des-foyers-universitaires\\\/\",\"url\":\"https:\\\/\\\/systematic-erp.com\\\/ar\\\/2024\\\/04\\\/16\\\/systematic-hebergement-le-digital-nouvelle-arme-des-foyers-universitaires\\\/\",\"name\":\"Systematic | H\u00e9bergement : Le digital, nouvelle arme des foyers universitaires - Systematic ERP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/systematic-erp.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/systematic-erp.com\\\/ar\\\/2024\\\/04\\\/16\\\/systematic-hebergement-le-digital-nouvelle-arme-des-foyers-universitaires\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/systematic-erp.com\\\/ar\\\/2024\\\/04\\\/16\\\/systematic-hebergement-le-digital-nouvelle-arme-des-foyers-universitaires\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/systematic-erp.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/La-presse-Le-digital-nouvelle-arme-des-foyers-universitaires-systematic.jpg\",\"datePublished\":\"2024-04-16T15:22:22+00:00\",\"dateModified\":\"2024-05-27T13:29:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/systematic-erp.com\\\/#\\\/schema\\\/person\\\/010337d3b3ba99dbdb74deb2c65423db\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/systematic-erp.com\\\/ar\\\/2024\\\/04\\\/16\\\/systematic-hebergement-le-digital-nouvelle-arme-des-foyers-universitaires\\\/#breadcrumb\"},\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/systematic-erp.com\\\/ar\\\/2024\\\/04\\\/16\\\/systematic-hebergement-le-digital-nouvelle-arme-des-foyers-universitaires\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/systematic-erp.com\\\/ar\\\/2024\\\/04\\\/16\\\/systematic-hebergement-le-digital-nouvelle-arme-des-foyers-universitaires\\\/#primaryimage\",\"url\":\"https:\\\/\\\/systematic-erp.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/La-presse-Le-digital-nouvelle-arme-des-foyers-universitaires-systematic.jpg\",\"contentUrl\":\"https:\\\/\\\/systematic-erp.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/La-presse-Le-digital-nouvelle-arme-des-foyers-universitaires-systematic.jpg\",\"width\":570,\"height\":396},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/systematic-erp.com\\\/ar\\\/2024\\\/04\\\/16\\\/systematic-hebergement-le-digital-nouvelle-arme-des-foyers-universitaires\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/systematic-erp.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Systematic | H\u00e9bergement : Le digital, nouvelle arme des foyers universitaires\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/systematic-erp.com\\\/#website\",\"url\":\"https:\\\/\\\/systematic-erp.com\\\/\",\"name\":\"Systematic Software Solutions\",\"description\":\"Software solution\",\"alternateName\":\"Systematic ERP\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/systematic-erp.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/systematic-erp.com\\\/#\\\/schema\\\/person\\\/010337d3b3ba99dbdb74deb2c65423db\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98aa6d15bd2101a3776cfb34fe37e68db2fd5ffb20d3ce47a9642bbd5d489609?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98aa6d15bd2101a3776cfb34fe37e68db2fd5ffb20d3ce47a9642bbd5d489609?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98aa6d15bd2101a3776cfb34fe37e68db2fd5ffb20d3ce47a9642bbd5d489609?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/systematic-erp.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Systematic | H\u00e9bergement : Le digital, nouvelle arme des foyers universitaires - Systematic ERP","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/systematic-erp.com\/ar\/2024\/04\/16\/systematic-hebergement-le-digital-nouvelle-arme-des-foyers-universitaires\/","og_locale":"ar_AR","og_type":"article","og_title":"Systematic | H\u00e9bergement : Le digital, nouvelle arme des foyers universitaires - Systematic ERP","og_description":"Systematech e r\u00e9ussi \u00e0 cr\u00e9er une plate-forme en ligne qui offre des solutions d\u2019h\u00e9bergement adapt\u00e9es aux besoins des \u00e9tudiants et surtout des foyers universitaires. Le coup d\u2019envoi de l\u2019ann\u00e9e universitaire a \u00e9t\u00e9 donn\u00e9 il y a quelques semaines, dans un contexte particulier li\u00e9 \u00e0 l\u2019\u00e9pi\u00acd\u00e9mie de Covid-19. Mais comme de coutume, le parcours s\u2019annonce assez [&hellip;]","og_url":"https:\/\/systematic-erp.com\/ar\/2024\/04\/16\/systematic-hebergement-le-digital-nouvelle-arme-des-foyers-universitaires\/","og_site_name":"Systematic ERP","article_publisher":"https:\/\/www.facebook.com\/SystematicSoftwareSolutions\/","article_published_time":"2024-04-16T15:22:22+00:00","article_modified_time":"2024-05-27T13:29:26+00:00","og_image":[{"width":570,"height":396,"url":"https:\/\/systematic-erp.com\/wp-content\/uploads\/2022\/04\/La-presse-Le-digital-nouvelle-arme-des-foyers-universitaires-systematic.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u0643\u064f\u062a\u0628 \u0628\u0648\u0627\u0633\u0637\u0629":"admin","\u0648\u0642\u062a \u0627\u0644\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u064f\u0642\u062f\u0651\u0631":"4 \u062f\u0642\u0627\u0626\u0642"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/systematic-erp.com\/ar\/2024\/04\/16\/systematic-hebergement-le-digital-nouvelle-arme-des-foyers-universitaires\/#article","isPartOf":{"@id":"https:\/\/systematic-erp.com\/ar\/2024\/04\/16\/systematic-hebergement-le-digital-nouvelle-arme-des-foyers-universitaires\/"},"author":{"name":"admin","@id":"https:\/\/systematic-erp.com\/#\/schema\/person\/010337d3b3ba99dbdb74deb2c65423db"},"headline":"Systematic | H\u00e9bergement : Le digital, nouvelle arme des foyers universitaires","datePublished":"2024-04-16T15:22:22+00:00","dateModified":"2024-05-27T13:29:26+00:00","mainEntityOfPage":{"@id":"https:\/\/systematic-erp.com\/ar\/2024\/04\/16\/systematic-hebergement-le-digital-nouvelle-arme-des-foyers-universitaires\/"},"wordCount":694,"image":{"@id":"https:\/\/systematic-erp.com\/ar\/2024\/04\/16\/systematic-hebergement-le-digital-nouvelle-arme-des-foyers-universitaires\/#primaryimage"},"thumbnailUrl":"https:\/\/systematic-erp.com\/wp-content\/uploads\/2022\/04\/La-presse-Le-digital-nouvelle-arme-des-foyers-universitaires-systematic.jpg","articleSection":["\u0635\u062d\u0627\u0641\u0629"],"inLanguage":"ar"},{"@type":"WebPage","@id":"https:\/\/systematic-erp.com\/ar\/2024\/04\/16\/systematic-hebergement-le-digital-nouvelle-arme-des-foyers-universitaires\/","url":"https:\/\/systematic-erp.com\/ar\/2024\/04\/16\/systematic-hebergement-le-digital-nouvelle-arme-des-foyers-universitaires\/","name":"Systematic | H\u00e9bergement : Le digital, nouvelle arme des foyers universitaires - Systematic ERP","isPartOf":{"@id":"https:\/\/systematic-erp.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/systematic-erp.com\/ar\/2024\/04\/16\/systematic-hebergement-le-digital-nouvelle-arme-des-foyers-universitaires\/#primaryimage"},"image":{"@id":"https:\/\/systematic-erp.com\/ar\/2024\/04\/16\/systematic-hebergement-le-digital-nouvelle-arme-des-foyers-universitaires\/#primaryimage"},"thumbnailUrl":"https:\/\/systematic-erp.com\/wp-content\/uploads\/2022\/04\/La-presse-Le-digital-nouvelle-arme-des-foyers-universitaires-systematic.jpg","datePublished":"2024-04-16T15:22:22+00:00","dateModified":"2024-05-27T13:29:26+00:00","author":{"@id":"https:\/\/systematic-erp.com\/#\/schema\/person\/010337d3b3ba99dbdb74deb2c65423db"},"breadcrumb":{"@id":"https:\/\/systematic-erp.com\/ar\/2024\/04\/16\/systematic-hebergement-le-digital-nouvelle-arme-des-foyers-universitaires\/#breadcrumb"},"inLanguage":"ar","potentialAction":[{"@type":"ReadAction","target":["https:\/\/systematic-erp.com\/ar\/2024\/04\/16\/systematic-hebergement-le-digital-nouvelle-arme-des-foyers-universitaires\/"]}]},{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/systematic-erp.com\/ar\/2024\/04\/16\/systematic-hebergement-le-digital-nouvelle-arme-des-foyers-universitaires\/#primaryimage","url":"https:\/\/systematic-erp.com\/wp-content\/uploads\/2022\/04\/La-presse-Le-digital-nouvelle-arme-des-foyers-universitaires-systematic.jpg","contentUrl":"https:\/\/systematic-erp.com\/wp-content\/uploads\/2022\/04\/La-presse-Le-digital-nouvelle-arme-des-foyers-universitaires-systematic.jpg","width":570,"height":396},{"@type":"BreadcrumbList","@id":"https:\/\/systematic-erp.com\/ar\/2024\/04\/16\/systematic-hebergement-le-digital-nouvelle-arme-des-foyers-universitaires\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/systematic-erp.com\/"},{"@type":"ListItem","position":2,"name":"Systematic | H\u00e9bergement : Le digital, nouvelle arme des foyers universitaires"}]},{"@type":"WebSite","@id":"https:\/\/systematic-erp.com\/#website","url":"https:\/\/systematic-erp.com\/","name":"Systematic Software Solutions","description":"Software solution","alternateName":"Systematic ERP","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/systematic-erp.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"},{"@type":"Person","@id":"https:\/\/systematic-erp.com\/#\/schema\/person\/010337d3b3ba99dbdb74deb2c65423db","name":"admin","image":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/secure.gravatar.com\/avatar\/98aa6d15bd2101a3776cfb34fe37e68db2fd5ffb20d3ce47a9642bbd5d489609?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/98aa6d15bd2101a3776cfb34fe37e68db2fd5ffb20d3ce47a9642bbd5d489609?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/98aa6d15bd2101a3776cfb34fe37e68db2fd5ffb20d3ce47a9642bbd5d489609?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/systematic-erp.com"]}]}},"_links":{"self":[{"href":"https:\/\/systematic-erp.com\/ar\/wp-json\/wp\/v2\/posts\/18233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/systematic-erp.com\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/systematic-erp.com\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/systematic-erp.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/systematic-erp.com\/ar\/wp-json\/wp\/v2\/comments?post=18233"}],"version-history":[{"count":0,"href":"https:\/\/systematic-erp.com\/ar\/wp-json\/wp\/v2\/posts\/18233\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/systematic-erp.com\/ar\/wp-json\/wp\/v2\/media\/16694"}],"wp:attachment":[{"href":"https:\/\/systematic-erp.com\/ar\/wp-json\/wp\/v2\/media?parent=18233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/systematic-erp.com\/ar\/wp-json\/wp\/v2\/categories?post=18233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/systematic-erp.com\/ar\/wp-json\/wp\/v2\/tags?post=18233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}